{"id":36928,"date":"2025-05-23T12:43:24","date_gmt":"2025-05-23T12:43:24","guid":{"rendered":"https:\/\/thisisadominoproject.org\/last-night-the-23rd-season-of-queer-zagreb-officially-opened\/"},"modified":"2025-07-11T10:16:11","modified_gmt":"2025-07-11T10:16:11","slug":"last-night-the-23rd-season-of-queer-zagreb-officially-opened","status":"publish","type":"post","link":"https:\/\/thisisadominoproject.org\/en\/last-night-the-23rd-season-of-queer-zagreb-officially-opened\/","title":{"rendered":"Last night the 23rd season of Queer Zagreb officially opened!"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"36928\" class=\"elementor elementor-36928 elementor-36427\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-28f8361c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"28f8361c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4a74f2aa\" data-id=\"4a74f2aa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2078bac8 elementor-widget elementor-widget-text-editor\" data-id=\"2078bac8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: justify;\">Last night, in front of a packed auditorium at the Zagreb Dance Center, we officially opened <strong>the 23rd season of Queer Zagreb<\/strong> . This year&#8217;s edition, dedicated to the theme <strong>Criminal Queer<\/strong> , began with an emotional and powerful premiere of the play <em><strong>All My Bodies \/ Todos mis cuerpos<\/strong><\/em> by Argentine director <strong>Gonzalo Quintana<\/strong> , in a solo performance by the exceptional actress <strong>Maiamar Abrodos<\/strong> \u2013 one of the first people in Argentina to legally change their gender identity, and who was personally presented with the new documents by then-president Cristina Kirchner. <\/p>\n<p style=\"text-align: justify;\">Conceived as a theater workshop in which Maiamar \u2013 a professor of performing arts at EMAD (the Metropolitan School of Dramatic Arts in Buenos Aires) \u2013 gives a lecture on the body, the play becomes a search for one\u2019s own image. Through Maiamar\u2019s story of transition, the struggle for identity, life under dictatorship, hormones, surgeries and art as a means of survival, <em><strong>All My Bodies \/ Todos mis cuerpos<\/strong><\/em> combines humor, music and archival footage into a documentary introspection of an extraordinary biography. <\/p>\n<p style=\"text-align: justify;\"><strong>You can see the performance that thrilled the audience last night today, May 23rd, at 8:00 PM at the Zagreb Dance Center. <\/strong>, and the program of the 23rd Queer Zagreb season continues until May 29th with a series of performances, exhibitions and discursive events at various locations in the city. A detailed schedule and information are available on our official website:   <a class=\"ck-link\" href=\"https:\/\/preview.convertkit-mail2.com\/click\/dpheh0hzhm\/aHR0cHM6Ly90aGlzaXNhZG9taW5vcHJvamVjdC5vcmcv\" target=\"_blank\" rel=\"noopener noreferrer\"> <\/a><a class=\"ck-link\" href=\"https:\/\/preview.convertkit-mail2.com\/click\/dpheh0hzhm\/aHR0cDovL3RoaXNpc2Fkb21pbm9wcm9qZWN0Lm9yZw==\" target=\"_blank\" rel=\"noopener noreferrer\">thisisadominoproject.org<\/a> .<\/p>\n<p style=\"text-align: justify;\"><strong>You can view photos from this unforgettable evening in the gallery below.<\/strong><\/p>\n<p>\n\t\t\t<style type='text\/css'>\n\t\t\t\t#gallery-1 {\n\t\t\t\t\tmargin: auto;\n\t\t\t\t}\n\t\t\t\t#gallery-1 .gallery-item {\n\t\t\t\t\tfloat: left;\n\t\t\t\t\tmargin-top: 10px;\n\t\t\t\t\ttext-align: center;\n\t\t\t\t\twidth: 20%;\n\t\t\t\t}\n\t\t\t\t#gallery-1 img {\n\t\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t\t}\n\t\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\t\tmargin-left: 0;\n\t\t\t\t}\n\t\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t\t<\/style>\n\t\t<div id='gallery-1' class='dt-gallery-container gallery galleryid-36928 gallery-columns-5 gallery-size-medium'><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer01_220525\" data-dt-img-description=\"\" data-large_image_width=\"1800\" data-large_image_height=\"1200\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer01_220525-scaled.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer01_220525-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer01_220525-300x200.jpg 300w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer01_220525-1024x683.jpg 1024w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer01_220525-768x512.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer01_220525-1536x1024.jpg 1536w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer01_220525-scaled.jpg 1800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer02_220525\" data-dt-img-description=\"\" data-large_image_width=\"1800\" data-large_image_height=\"1237\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer02_220525-scaled.jpg'><img decoding=\"async\" width=\"300\" height=\"206\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer02_220525-300x206.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer02_220525-300x206.jpg 300w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer02_220525-1024x704.jpg 1024w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer02_220525-768x528.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer02_220525-1536x1056.jpg 1536w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer02_220525-scaled.jpg 1800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer03_220525\" data-dt-img-description=\"\" data-large_image_width=\"1800\" data-large_image_height=\"1200\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer03_220525-scaled.jpg'><img decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer03_220525-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer03_220525-300x200.jpg 300w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer03_220525-1024x683.jpg 1024w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer03_220525-768x512.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer03_220525-1536x1024.jpg 1536w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer03_220525-scaled.jpg 1800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer04_220525\" data-dt-img-description=\"\" data-large_image_width=\"1800\" data-large_image_height=\"1200\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer04_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer04_220525-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer04_220525-300x200.jpg 300w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer04_220525-1024x683.jpg 1024w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer04_220525-768x512.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer04_220525-1536x1024.jpg 1536w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer04_220525-scaled.jpg 1800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer05_220525\" data-dt-img-description=\"\" data-large_image_width=\"1800\" data-large_image_height=\"1283\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer05_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"214\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer05_220525-300x214.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer05_220525-300x214.jpg 300w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer05_220525-1024x730.jpg 1024w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer05_220525-768x547.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer05_220525-1536x1094.jpg 1536w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer05_220525-scaled.jpg 1800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer06_220525\" data-dt-img-description=\"\" data-large_image_width=\"1800\" data-large_image_height=\"1238\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer06_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"206\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer06_220525-300x206.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer06_220525-300x206.jpg 300w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer06_220525-1024x704.jpg 1024w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer06_220525-768x528.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer06_220525-1536x1056.jpg 1536w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer06_220525-scaled.jpg 1800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer07_220525\" data-dt-img-description=\"\" data-large_image_width=\"1800\" data-large_image_height=\"1246\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer07_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"208\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer07_220525-300x208.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer07_220525-300x208.jpg 300w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer07_220525-1024x709.jpg 1024w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer07_220525-768x532.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer07_220525-1536x1063.jpg 1536w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer07_220525-scaled.jpg 1800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer08_220525\" data-dt-img-description=\"\" data-large_image_width=\"1643\" data-large_image_height=\"2560\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer08_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"193\" height=\"300\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer08_220525-193x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer08_220525-193x300.jpg 193w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer08_220525-657x1024.jpg 657w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer08_220525-768x1197.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer08_220525-986x1536.jpg 986w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer08_220525-1314x2048.jpg 1314w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer08_220525-scaled.jpg 1643w\" sizes=\"(max-width: 193px) 100vw, 193px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer09_220525\" data-dt-img-description=\"\" data-large_image_width=\"1968\" data-large_image_height=\"1200\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer09_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"183\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer09_220525-300x183.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer09_220525-300x183.jpg 300w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer09_220525-1024x624.jpg 1024w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer09_220525-768x468.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer09_220525-1536x937.jpg 1536w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer09_220525-scaled.jpg 1968w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer10_220525\" data-dt-img-description=\"\" data-large_image_width=\"1802\" data-large_image_height=\"1200\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer10_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer10_220525-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-36447\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer10_220525-300x200.jpg 300w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer10_220525-1024x682.jpg 1024w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer10_220525-768x511.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer10_220525-1536x1023.jpg 1536w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer10_220525-scaled.jpg 1802w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t<\/dt>\n\t\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-36447'>\n\t\t\t\t\tAll my bodies by Gonzalo Quintana\n\t\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer11_220525\" data-dt-img-description=\"\" data-large_image_width=\"1583\" data-large_image_height=\"2560\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer11_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"185\" height=\"300\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer11_220525-185x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer11_220525-185x300.jpg 185w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer11_220525-633x1024.jpg 633w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer11_220525-768x1242.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer11_220525-950x1536.jpg 950w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer11_220525-1266x2048.jpg 1266w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer11_220525-scaled.jpg 1583w\" sizes=\"(max-width: 185px) 100vw, 185px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer12_220525\" data-dt-img-description=\"\" data-large_image_width=\"1707\" data-large_image_height=\"2560\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer12_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"300\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer12_220525-200x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer12_220525-200x300.jpg 200w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer12_220525-683x1024.jpg 683w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer12_220525-768x1152.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer12_220525-1024x1536.jpg 1024w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer12_220525-1365x2048.jpg 1365w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer12_220525-scaled.jpg 1707w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer13_220525\" data-dt-img-description=\"\" data-large_image_width=\"1591\" data-large_image_height=\"2560\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer13_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"186\" height=\"300\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer13_220525-186x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer13_220525-186x300.jpg 186w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer13_220525-636x1024.jpg 636w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer13_220525-768x1236.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer13_220525-954x1536.jpg 954w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer13_220525-1272x2048.jpg 1272w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer13_220525-scaled.jpg 1591w\" sizes=\"(max-width: 186px) 100vw, 186px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer14_220525\" data-dt-img-description=\"\" data-large_image_width=\"1800\" data-large_image_height=\"1200\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer14_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer14_220525-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer14_220525-300x200.jpg 300w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer14_220525-1024x683.jpg 1024w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer14_220525-768x512.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer14_220525-1536x1024.jpg 1536w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer14_220525-scaled.jpg 1800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer15_220525\" data-dt-img-description=\"\" data-large_image_width=\"1800\" data-large_image_height=\"1200\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer15_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer15_220525-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer15_220525-300x200.jpg 300w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer15_220525-1024x683.jpg 1024w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer15_220525-768x512.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer15_220525-1536x1024.jpg 1536w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer15_220525-scaled.jpg 1800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer16_220525\" data-dt-img-description=\"\" data-large_image_width=\"1900\" data-large_image_height=\"1200\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer16_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"190\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer16_220525-300x190.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-36459\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer16_220525-300x190.jpg 300w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer16_220525-1024x647.jpg 1024w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer16_220525-768x485.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer16_220525-1536x970.jpg 1536w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer16_220525-2048x1294.jpg 1899w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer16_220525-scaled.jpg 1900w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t<\/dt>\n\t\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-36459'>\n\t\t\t\t\tAll my bodies by Gonzalo Quintana\n\t\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer17_220525\" data-dt-img-description=\"\" data-large_image_width=\"1800\" data-large_image_height=\"1200\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer17_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer17_220525-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer17_220525-300x200.jpg 300w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer17_220525-1024x683.jpg 1024w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer17_220525-768x512.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer17_220525-1536x1024.jpg 1536w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer17_220525-scaled.jpg 1800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer18_220525\" data-dt-img-description=\"\" data-large_image_width=\"1800\" data-large_image_height=\"1200\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer18_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer18_220525-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-36463\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer18_220525-300x200.jpg 300w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer18_220525-1024x683.jpg 1024w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer18_220525-768x512.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer18_220525-1536x1024.jpg 1536w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer18_220525-scaled.jpg 1800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t<\/dt>\n\t\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-36463'>\n\t\t\t\t\tAll my bodies by Gonzalo Quintana\n\t\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer19_220525\" data-dt-img-description=\"\" data-large_image_width=\"1889\" data-large_image_height=\"1200\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer19_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"191\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer19_220525-300x191.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer19_220525-300x191.jpg 300w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer19_220525-1024x650.jpg 1024w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer19_220525-768x488.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer19_220525-1536x976.jpg 1536w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer19_220525-scaled.jpg 1889w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer20_220525\" data-dt-img-description=\"\" data-large_image_width=\"1800\" data-large_image_height=\"1200\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer20_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer20_220525-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer20_220525-300x200.jpg 300w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer20_220525-1024x683.jpg 1024w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer20_220525-768x512.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer20_220525-1536x1024.jpg 1536w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer20_220525-scaled.jpg 1800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer21_220525\" data-dt-img-description=\"\" data-large_image_width=\"1800\" data-large_image_height=\"1200\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer21_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer21_220525-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer21_220525-300x200.jpg 300w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer21_220525-1024x683.jpg 1024w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer21_220525-768x512.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer21_220525-1536x1024.jpg 1536w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer21_220525-scaled.jpg 1800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer22_220525\" data-dt-img-description=\"\" data-large_image_width=\"1879\" data-large_image_height=\"1200\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer22_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"192\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer22_220525-300x192.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer22_220525-300x192.jpg 300w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer22_220525-1024x654.jpg 1024w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer22_220525-768x490.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer22_220525-1536x981.jpg 1536w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer22_220525-scaled.jpg 1879w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer23_220525\" data-dt-img-description=\"\" data-large_image_width=\"1800\" data-large_image_height=\"1302\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer23_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"217\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer23_220525-300x217.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer23_220525-300x217.jpg 300w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer23_220525-1024x741.jpg 1024w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer23_220525-768x556.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer23_220525-1536x1111.jpg 1536w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer23_220525-scaled.jpg 1800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer24_220525\" data-dt-img-description=\"\" data-large_image_width=\"1800\" data-large_image_height=\"1209\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer24_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"201\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer24_220525-300x201.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-36475\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer24_220525-300x201.jpg 300w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer24_220525-1024x688.jpg 1024w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer24_220525-768x516.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer24_220525-1536x1031.jpg 1536w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer24_220525-scaled.jpg 1800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t<\/dt>\n\t\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-36475'>\n\t\t\t\t\tAll my bodies by Gonzalo Quintana\n\t\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer25_220525\" data-dt-img-description=\"\" data-large_image_width=\"1800\" data-large_image_height=\"1200\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer25_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer25_220525-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer25_220525-300x200.jpg 300w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer25_220525-1024x683.jpg 1024w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer25_220525-768x512.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer25_220525-1536x1024.jpg 1536w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer25_220525-scaled.jpg 1800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer26_220525\" data-dt-img-description=\"\" data-large_image_width=\"1807\" data-large_image_height=\"1200\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer26_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"199\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer26_220525-300x199.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer26_220525-300x199.jpg 300w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer26_220525-1024x680.jpg 1024w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer26_220525-768x510.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer26_220525-1536x1020.jpg 1536w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer26_220525-scaled.jpg 1807w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer27_220525\" data-dt-img-description=\"\" data-large_image_width=\"1800\" data-large_image_height=\"1200\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer27_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer27_220525-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer27_220525-300x200.jpg 300w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer27_220525-1024x683.jpg 1024w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer27_220525-768x512.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer27_220525-1536x1024.jpg 1536w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer27_220525-scaled.jpg 1800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer28_220525\" data-dt-img-description=\"\" data-large_image_width=\"1586\" data-large_image_height=\"2560\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer28_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"186\" height=\"300\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer28_220525-186x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer28_220525-186x300.jpg 186w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer28_220525-635x1024.jpg 635w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer28_220525-768x1239.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer28_220525-952x1536.jpg 952w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer28_220525-1269x2048.jpg 1269w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer28_220525-scaled.jpg 1586w\" sizes=\"(max-width: 186px) 100vw, 186px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer29_220525\" data-dt-img-description=\"\" data-large_image_width=\"1861\" data-large_image_height=\"1200\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer29_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"194\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer29_220525-300x194.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-36485\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer29_220525-300x194.jpg 300w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer29_220525-1024x660.jpg 1024w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer29_220525-768x495.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer29_220525-1536x991.jpg 1536w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer29_220525-2048x1321.jpg 1860w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer29_220525-scaled.jpg 1861w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t<\/dt>\n\t\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-36485'>\n\t\t\t\t\tAll my bodies by Gonzalo Quintana\n\t\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer30_220525\" data-dt-img-description=\"\" data-large_image_width=\"1800\" data-large_image_height=\"2280\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer30_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"237\" height=\"300\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer30_220525-237x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer30_220525-237x300.jpg 237w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer30_220525-808x1024.jpg 808w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer30_220525-768x973.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer30_220525-1212x1536.jpg 1212w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer30_220525-1616x2048.jpg 1616w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer30_220525-scaled.jpg 1800w\" sizes=\"(max-width: 237px) 100vw, 237px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer31_220525\" data-dt-img-description=\"\" data-large_image_width=\"1687\" data-large_image_height=\"2560\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer31_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"198\" height=\"300\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer31_220525-198x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer31_220525-198x300.jpg 198w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer31_220525-675x1024.jpg 675w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer31_220525-768x1165.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer31_220525-1012x1536.jpg 1012w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer31_220525-1350x2048.jpg 1350w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer31_220525-scaled.jpg 1687w\" sizes=\"(max-width: 198px) 100vw, 198px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer32_220525\" data-dt-img-description=\"\" data-large_image_width=\"1800\" data-large_image_height=\"1214\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer32_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"202\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer32_220525-300x202.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-36491\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer32_220525-300x202.jpg 300w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer32_220525-1024x691.jpg 1024w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer32_220525-768x518.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer32_220525-1536x1036.jpg 1536w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer32_220525-scaled.jpg 1800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t<\/dt>\n\t\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-36491'>\n\t\t\t\t\tAll my bodies by Gonzalo Quintana\n\t\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer33_220525\" data-dt-img-description=\"\" data-large_image_width=\"1707\" data-large_image_height=\"2560\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer33_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"300\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer33_220525-200x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer33_220525-200x300.jpg 200w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer33_220525-683x1024.jpg 683w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer33_220525-768x1152.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer33_220525-1024x1536.jpg 1024w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer33_220525-1365x2048.jpg 1365w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer33_220525-scaled.jpg 1707w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer34_220525\" data-dt-img-description=\"\" data-large_image_width=\"1800\" data-large_image_height=\"1240\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer34_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"207\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer34_220525-300x207.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer34_220525-300x207.jpg 300w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer34_220525-1024x706.jpg 1024w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer34_220525-768x529.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer34_220525-1536x1058.jpg 1536w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer34_220525-scaled.jpg 1800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer35_220525\" data-dt-img-description=\"\" data-large_image_width=\"1800\" data-large_image_height=\"1200\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer35_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer35_220525-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer35_220525-300x200.jpg 300w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer35_220525-1024x683.jpg 1024w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer35_220525-768x512.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer35_220525-1536x1024.jpg 1536w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer35_220525-scaled.jpg 1800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer36_220525\" data-dt-img-description=\"\" data-large_image_width=\"1800\" data-large_image_height=\"1200\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer36_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer36_220525-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer36_220525-300x200.jpg 300w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer36_220525-1024x683.jpg 1024w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer36_220525-768x512.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer36_220525-1536x1024.jpg 1536w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer36_220525-scaled.jpg 1800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer37_220525\" data-dt-img-description=\"\" data-large_image_width=\"1800\" data-large_image_height=\"1200\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer37_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer37_220525-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer37_220525-300x200.jpg 300w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer37_220525-1024x683.jpg 1024w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer37_220525-768x512.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer37_220525-1536x1024.jpg 1536w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer37_220525-scaled.jpg 1800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer38_220525\" data-dt-img-description=\"\" data-large_image_width=\"1800\" data-large_image_height=\"1218\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer38_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"203\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer38_220525-300x203.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer38_220525-300x203.jpg 300w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer38_220525-1024x693.jpg 1024w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer38_220525-768x520.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer38_220525-1536x1039.jpg 1536w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer38_220525-scaled.jpg 1800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer39_220525\" data-dt-img-description=\"\" data-large_image_width=\"1800\" data-large_image_height=\"1200\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer39_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer39_220525-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer39_220525-300x200.jpg 300w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer39_220525-1024x683.jpg 1024w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer39_220525-768x512.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer39_220525-1536x1024.jpg 1536w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer39_220525-scaled.jpg 1800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer40_220525\" data-dt-img-description=\"\" data-large_image_width=\"1800\" data-large_image_height=\"1235\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer40_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"206\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer40_220525-300x206.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer40_220525-300x206.jpg 300w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer40_220525-1024x702.jpg 1024w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer40_220525-768x527.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer40_220525-1536x1053.jpg 1536w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer40_220525-scaled.jpg 1800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer41_220525\" data-dt-img-description=\"\" data-large_image_width=\"1800\" data-large_image_height=\"2477\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer41_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"218\" height=\"300\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer41_220525-218x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer41_220525-218x300.jpg 218w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer41_220525-744x1024.jpg 744w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer41_220525-768x1057.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer41_220525-1116x1536.jpg 1116w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer41_220525-1488x2048.jpg 1488w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer41_220525-scaled.jpg 1800w\" sizes=\"(max-width: 218px) 100vw, 218px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer42_220525\" data-dt-img-description=\"\" data-large_image_width=\"1800\" data-large_image_height=\"1200\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer42_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer42_220525-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer42_220525-300x200.jpg 300w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer42_220525-1024x683.jpg 1024w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer42_220525-768x512.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer42_220525-1536x1024.jpg 1536w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer42_220525-scaled.jpg 1800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer43_220525\" data-dt-img-description=\"\" data-large_image_width=\"1662\" data-large_image_height=\"2560\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer43_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"195\" height=\"300\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer43_220525-195x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer43_220525-195x300.jpg 195w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer43_220525-665x1024.jpg 665w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer43_220525-768x1183.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer43_220525-997x1536.jpg 997w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer43_220525-1329x2048.jpg 1329w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer43_220525-scaled.jpg 1662w\" sizes=\"(max-width: 195px) 100vw, 195px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer44_220525\" data-dt-img-description=\"\" data-large_image_width=\"1800\" data-large_image_height=\"1215\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer44_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"203\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer44_220525-300x203.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer44_220525-300x203.jpg 300w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer44_220525-1024x691.jpg 1024w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer44_220525-768x518.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer44_220525-1536x1037.jpg 1536w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer44_220525-scaled.jpg 1800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer45_220525\" data-dt-img-description=\"\" data-large_image_width=\"1800\" data-large_image_height=\"1240\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer45_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"207\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer45_220525-300x207.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer45_220525-300x207.jpg 300w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer45_220525-1024x706.jpg 1024w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer45_220525-768x529.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer45_220525-1536x1058.jpg 1536w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer45_220525-scaled.jpg 1800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer46_220525\" data-dt-img-description=\"\" data-large_image_width=\"1800\" data-large_image_height=\"1200\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer46_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer46_220525-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer46_220525-300x200.jpg 300w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer46_220525-1024x683.jpg 1024w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer46_220525-768x512.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer46_220525-1536x1024.jpg 1536w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer46_220525-scaled.jpg 1800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer47_220525\" data-dt-img-description=\"\" data-large_image_width=\"1810\" data-large_image_height=\"1200\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer47_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"199\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer47_220525-300x199.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer47_220525-300x199.jpg 300w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer47_220525-1024x679.jpg 1024w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer47_220525-768x509.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer47_220525-1536x1018.jpg 1536w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer47_220525-2048x1357.jpg 1811w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer47_220525-scaled.jpg 1810w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"queer48_220525\" data-dt-img-description=\"\" data-large_image_width=\"1800\" data-large_image_height=\"1293\"href='https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer48_220525-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"215\" src=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer48_220525-300x215.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer48_220525-300x215.jpg 300w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer48_220525-1024x735.jpg 1024w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer48_220525-768x552.jpg 768w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer48_220525-1536x1103.jpg 1536w, https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer48_220525-scaled.jpg 1800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl>\n\t\t\t\t<br style='clear: both' \/>\n\t\t\t<\/div>\n\n<p> <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Last night, in front of a packed auditorium at the Zagreb Dance Center, we officially opened the 23rd season of Queer Zagreb . This year&#8217;s edition, dedicated to the theme Criminal Queer , began with an emotional and powerful premiere of the play All My Bodies \/ Todos mis cuerpos by Argentine director Gonzalo Quintana&hellip;<\/p>\n","protected":false},"author":1,"featured_media":36525,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2005,2451,2357],"tags":[2453,2454,2455,2246,2370,2363,2367],"class_list":["post-36928","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-en","category-queer-zagreb-season","category-queer-zagreb-season-2025","tag-23-queer-zagreb-en","tag-all-my-bodies-en","tag-all-my-bodies-en-2","tag-gonzalo-quintana-en","tag-maiamar-abrodos-en","tag-queer-zagreb-season","tag-queer-zagreb-season-2025"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Last night the 23rd season of Queer Zagreb officially opened! - Udruga Domino<\/title>\n<meta name=\"description\" content=\"Last night, in front of a packed auditorium at the Zagreb Dance Center, we officially opened the 23rd season of Queer Zagreb. This year&#039;s edition, dedicated to the theme of Criminal Queer, began with the emotional and powerful premiere of the play All My Bodies \/ Todos mis cuerpos by Argentine director Gonzalo Quintana, in a solo performance by the exceptional actress Maiamar Abrodos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thisisadominoproject.org\/en\/last-night-the-23rd-season-of-queer-zagreb-officially-opened\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Last night the 23rd season of Queer Zagreb officially opened! - Udruga Domino\" \/>\n<meta property=\"og:description\" content=\"Last night, in front of a packed auditorium at the Zagreb Dance Center, we officially opened the 23rd season of Queer Zagreb. This year&#039;s edition, dedicated to the theme of Criminal Queer, began with the emotional and powerful premiere of the play All My Bodies \/ Todos mis cuerpos by Argentine director Gonzalo Quintana, in a solo performance by the exceptional actress Maiamar Abrodos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thisisadominoproject.org\/en\/last-night-the-23rd-season-of-queer-zagreb-officially-opened\/\" \/>\n<meta property=\"og:site_name\" content=\"Udruga Domino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/thisisadominoproject\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-23T12:43:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-11T10:16:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer32_220525-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1214\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/thisisadominoproject.org\\\/en\\\/last-night-the-23rd-season-of-queer-zagreb-officially-opened\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thisisadominoproject.org\\\/en\\\/last-night-the-23rd-season-of-queer-zagreb-officially-opened\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/thisisadominoproject.org\\\/en\\\/#\\\/schema\\\/person\\\/a2aa55b889ff99570530210c94e5c77c\"},\"headline\":\"Last night the 23rd season of Queer Zagreb officially opened!\",\"datePublished\":\"2025-05-23T12:43:24+00:00\",\"dateModified\":\"2025-07-11T10:16:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/thisisadominoproject.org\\\/en\\\/last-night-the-23rd-season-of-queer-zagreb-officially-opened\\\/\"},\"wordCount\":262,\"publisher\":{\"@id\":\"https:\\\/\\\/thisisadominoproject.org\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/thisisadominoproject.org\\\/en\\\/last-night-the-23rd-season-of-queer-zagreb-officially-opened\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thisisadominoproject.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/queer32_220525-1-scaled.jpg\",\"keywords\":[\"23 Queer Zagreb\",\"All my bodies\",\"All my bodies\",\"Gonzalo Quintana\",\"Maiamar Abrodos\",\"Queer Zagreb Season\",\"queer zagreb season 2025\"],\"articleSection\":[\"NEWS\",\"Queer Zagreb Season\",\"Queer Zagreb Season 2025\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/thisisadominoproject.org\\\/en\\\/last-night-the-23rd-season-of-queer-zagreb-officially-opened\\\/\",\"url\":\"https:\\\/\\\/thisisadominoproject.org\\\/en\\\/last-night-the-23rd-season-of-queer-zagreb-officially-opened\\\/\",\"name\":\"Last night the 23rd season of Queer Zagreb officially opened! - Udruga Domino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thisisadominoproject.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/thisisadominoproject.org\\\/en\\\/last-night-the-23rd-season-of-queer-zagreb-officially-opened\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/thisisadominoproject.org\\\/en\\\/last-night-the-23rd-season-of-queer-zagreb-officially-opened\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thisisadominoproject.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/queer32_220525-1-scaled.jpg\",\"datePublished\":\"2025-05-23T12:43:24+00:00\",\"dateModified\":\"2025-07-11T10:16:11+00:00\",\"description\":\"Last night, in front of a packed auditorium at the Zagreb Dance Center, we officially opened the 23rd season of Queer Zagreb. This year's edition, dedicated to the theme of Criminal Queer, began with the emotional and powerful premiere of the play All My Bodies \\\/ Todos mis cuerpos by Argentine director Gonzalo Quintana, in a solo performance by the exceptional actress Maiamar Abrodos\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thisisadominoproject.org\\\/en\\\/last-night-the-23rd-season-of-queer-zagreb-officially-opened\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/thisisadominoproject.org\\\/en\\\/last-night-the-23rd-season-of-queer-zagreb-officially-opened\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/thisisadominoproject.org\\\/en\\\/last-night-the-23rd-season-of-queer-zagreb-officially-opened\\\/#primaryimage\",\"url\":\"https:\\\/\\\/thisisadominoproject.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/queer32_220525-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/thisisadominoproject.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/queer32_220525-1-scaled.jpg\",\"width\":1800,\"height\":1214},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thisisadominoproject.org\\\/en\\\/last-night-the-23rd-season-of-queer-zagreb-officially-opened\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Po\u010detna\",\"item\":\"https:\\\/\\\/thisisadominoproject.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Last night the 23rd season of Queer Zagreb officially opened!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thisisadominoproject.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/thisisadominoproject.org\\\/en\\\/\",\"name\":\"Udruga Domino\",\"description\":\"This is a Domino project\",\"publisher\":{\"@id\":\"https:\\\/\\\/thisisadominoproject.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thisisadominoproject.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/thisisadominoproject.org\\\/en\\\/#organization\",\"name\":\"Udruga Domino\",\"url\":\"https:\\\/\\\/thisisadominoproject.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/thisisadominoproject.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/thisisadominoproject.org\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/cropped-ICON.png\",\"contentUrl\":\"https:\\\/\\\/thisisadominoproject.org\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/cropped-ICON.png\",\"width\":512,\"height\":512,\"caption\":\"Udruga Domino\"},\"image\":{\"@id\":\"https:\\\/\\\/thisisadominoproject.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/thisisadominoproject\",\"https:\\\/\\\/www.instagram.com\\\/this_is_a_domino_project\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/thisisadominoproject.org\\\/en\\\/#\\\/schema\\\/person\\\/a2aa55b889ff99570530210c94e5c77c\",\"name\":\"admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Last night the 23rd season of Queer Zagreb officially opened! - Udruga Domino","description":"Last night, in front of a packed auditorium at the Zagreb Dance Center, we officially opened the 23rd season of Queer Zagreb. This year's edition, dedicated to the theme of Criminal Queer, began with the emotional and powerful premiere of the play All My Bodies \/ Todos mis cuerpos by Argentine director Gonzalo Quintana, in a solo performance by the exceptional actress Maiamar Abrodos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thisisadominoproject.org\/en\/last-night-the-23rd-season-of-queer-zagreb-officially-opened\/","og_locale":"en_US","og_type":"article","og_title":"Last night the 23rd season of Queer Zagreb officially opened! - Udruga Domino","og_description":"Last night, in front of a packed auditorium at the Zagreb Dance Center, we officially opened the 23rd season of Queer Zagreb. This year's edition, dedicated to the theme of Criminal Queer, began with the emotional and powerful premiere of the play All My Bodies \/ Todos mis cuerpos by Argentine director Gonzalo Quintana, in a solo performance by the exceptional actress Maiamar Abrodos","og_url":"https:\/\/thisisadominoproject.org\/en\/last-night-the-23rd-season-of-queer-zagreb-officially-opened\/","og_site_name":"Udruga Domino","article_publisher":"https:\/\/www.facebook.com\/thisisadominoproject","article_published_time":"2025-05-23T12:43:24+00:00","article_modified_time":"2025-07-11T10:16:11+00:00","og_image":[{"width":1800,"height":1214,"url":"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer32_220525-1-scaled.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/thisisadominoproject.org\/en\/last-night-the-23rd-season-of-queer-zagreb-officially-opened\/#article","isPartOf":{"@id":"https:\/\/thisisadominoproject.org\/en\/last-night-the-23rd-season-of-queer-zagreb-officially-opened\/"},"author":{"name":"admin","@id":"https:\/\/thisisadominoproject.org\/en\/#\/schema\/person\/a2aa55b889ff99570530210c94e5c77c"},"headline":"Last night the 23rd season of Queer Zagreb officially opened!","datePublished":"2025-05-23T12:43:24+00:00","dateModified":"2025-07-11T10:16:11+00:00","mainEntityOfPage":{"@id":"https:\/\/thisisadominoproject.org\/en\/last-night-the-23rd-season-of-queer-zagreb-officially-opened\/"},"wordCount":262,"publisher":{"@id":"https:\/\/thisisadominoproject.org\/en\/#organization"},"image":{"@id":"https:\/\/thisisadominoproject.org\/en\/last-night-the-23rd-season-of-queer-zagreb-officially-opened\/#primaryimage"},"thumbnailUrl":"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer32_220525-1-scaled.jpg","keywords":["23 Queer Zagreb","All my bodies","All my bodies","Gonzalo Quintana","Maiamar Abrodos","Queer Zagreb Season","queer zagreb season 2025"],"articleSection":["NEWS","Queer Zagreb Season","Queer Zagreb Season 2025"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/thisisadominoproject.org\/en\/last-night-the-23rd-season-of-queer-zagreb-officially-opened\/","url":"https:\/\/thisisadominoproject.org\/en\/last-night-the-23rd-season-of-queer-zagreb-officially-opened\/","name":"Last night the 23rd season of Queer Zagreb officially opened! - Udruga Domino","isPartOf":{"@id":"https:\/\/thisisadominoproject.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/thisisadominoproject.org\/en\/last-night-the-23rd-season-of-queer-zagreb-officially-opened\/#primaryimage"},"image":{"@id":"https:\/\/thisisadominoproject.org\/en\/last-night-the-23rd-season-of-queer-zagreb-officially-opened\/#primaryimage"},"thumbnailUrl":"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer32_220525-1-scaled.jpg","datePublished":"2025-05-23T12:43:24+00:00","dateModified":"2025-07-11T10:16:11+00:00","description":"Last night, in front of a packed auditorium at the Zagreb Dance Center, we officially opened the 23rd season of Queer Zagreb. This year's edition, dedicated to the theme of Criminal Queer, began with the emotional and powerful premiere of the play All My Bodies \/ Todos mis cuerpos by Argentine director Gonzalo Quintana, in a solo performance by the exceptional actress Maiamar Abrodos","breadcrumb":{"@id":"https:\/\/thisisadominoproject.org\/en\/last-night-the-23rd-season-of-queer-zagreb-officially-opened\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thisisadominoproject.org\/en\/last-night-the-23rd-season-of-queer-zagreb-officially-opened\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/thisisadominoproject.org\/en\/last-night-the-23rd-season-of-queer-zagreb-officially-opened\/#primaryimage","url":"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer32_220525-1-scaled.jpg","contentUrl":"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2025\/05\/queer32_220525-1-scaled.jpg","width":1800,"height":1214},{"@type":"BreadcrumbList","@id":"https:\/\/thisisadominoproject.org\/en\/last-night-the-23rd-season-of-queer-zagreb-officially-opened\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Po\u010detna","item":"https:\/\/thisisadominoproject.org\/en\/"},{"@type":"ListItem","position":2,"name":"Last night the 23rd season of Queer Zagreb officially opened!"}]},{"@type":"WebSite","@id":"https:\/\/thisisadominoproject.org\/en\/#website","url":"https:\/\/thisisadominoproject.org\/en\/","name":"Udruga Domino","description":"This is a Domino project","publisher":{"@id":"https:\/\/thisisadominoproject.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thisisadominoproject.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/thisisadominoproject.org\/en\/#organization","name":"Udruga Domino","url":"https:\/\/thisisadominoproject.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/thisisadominoproject.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2018\/04\/cropped-ICON.png","contentUrl":"https:\/\/thisisadominoproject.org\/wp-content\/uploads\/2018\/04\/cropped-ICON.png","width":512,"height":512,"caption":"Udruga Domino"},"image":{"@id":"https:\/\/thisisadominoproject.org\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/thisisadominoproject","https:\/\/www.instagram.com\/this_is_a_domino_project\/"]},{"@type":"Person","@id":"https:\/\/thisisadominoproject.org\/en\/#\/schema\/person\/a2aa55b889ff99570530210c94e5c77c","name":"admin"}]}},"_links":{"self":[{"href":"https:\/\/thisisadominoproject.org\/en\/wp-json\/wp\/v2\/posts\/36928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thisisadominoproject.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thisisadominoproject.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thisisadominoproject.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thisisadominoproject.org\/en\/wp-json\/wp\/v2\/comments?post=36928"}],"version-history":[{"count":0,"href":"https:\/\/thisisadominoproject.org\/en\/wp-json\/wp\/v2\/posts\/36928\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thisisadominoproject.org\/en\/wp-json\/wp\/v2\/media\/36525"}],"wp:attachment":[{"href":"https:\/\/thisisadominoproject.org\/en\/wp-json\/wp\/v2\/media?parent=36928"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thisisadominoproject.org\/en\/wp-json\/wp\/v2\/categories?post=36928"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thisisadominoproject.org\/en\/wp-json\/wp\/v2\/tags?post=36928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}